{"id":735,"count":2,"description":"","link":"https:\/\/garlicmysoul.com\/blog\/tag\/pretzels\/","name":"pretzels","slug":"pretzels","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>pretzels Archives - Garlic My Soul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/garlicmysoul.com\/blog\/tag\/pretzels\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"pretzels Archives - Garlic My Soul\" \/>\n<meta property=\"og:url\" content=\"https:\/\/garlicmysoul.com\/blog\/tag\/pretzels\/\" \/>\n<meta property=\"og:site_name\" content=\"Garlic My Soul\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/garlicmysoul.com\\\/blog\\\/tag\\\/pretzels\\\/\",\"url\":\"https:\\\/\\\/garlicmysoul.com\\\/blog\\\/tag\\\/pretzels\\\/\",\"name\":\"pretzels Archives - Garlic My Soul\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/garlicmysoul.com\\\/blog\\\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/garlicmysoul.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/garlicmysoul.com\\\/blog\\\/\",\"name\":\"Garlic My Soul\",\"description\":\"A cooking blog from Jennie Palluzzi, who believes in real food for real life.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/garlicmysoul.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"pretzels Archives - Garlic My Soul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/garlicmysoul.com\/blog\/tag\/pretzels\/","og_locale":"en_US","og_type":"article","og_title":"pretzels Archives - Garlic My Soul","og_url":"https:\/\/garlicmysoul.com\/blog\/tag\/pretzels\/","og_site_name":"Garlic My Soul","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/garlicmysoul.com\/blog\/tag\/pretzels\/","url":"https:\/\/garlicmysoul.com\/blog\/tag\/pretzels\/","name":"pretzels Archives - Garlic My Soul","isPartOf":{"@id":"https:\/\/garlicmysoul.com\/blog\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/garlicmysoul.com\/blog\/#website","url":"https:\/\/garlicmysoul.com\/blog\/","name":"Garlic My Soul","description":"A cooking blog from Jennie Palluzzi, who believes in real food for real life.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/garlicmysoul.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/garlicmysoul.com\/blog\/wp-json\/wp\/v2\/tags\/735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/garlicmysoul.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/garlicmysoul.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/garlicmysoul.com\/blog\/wp-json\/wp\/v2\/posts?tags=735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}